{"id":744,"date":"2025-01-12T18:59:22","date_gmt":"2025-01-12T17:59:22","guid":{"rendered":"http:\/\/www.lesvelosdarthur.fr\/?p=744"},"modified":"2025-08-29T14:16:46","modified_gmt":"2025-08-29T12:16:46","slug":"pourquoi-le-velo-cargo-en-kit","status":"publish","type":"post","link":"https:\/\/www.lesvelosdarthur.fr\/index.php\/2025\/01\/12\/pourquoi-le-velo-cargo-en-kit\/","title":{"rendered":"Pourquoi le v\u00e9lo cargo en kit ?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Nous d\u00e9marrons ici une s\u00e9rie de publications concernant notre conception et vision du v\u00e9lo et plus particuli\u00e8rement dans un premier temps celles du v\u00e9lo cargo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous apporterons \u00e9galement des informations sur l\u2019actualit\u00e9 du v\u00e9lo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous sommes aujourd\u2019hui de plus en plus nombreux \u00e0 comprendre l\u2019int\u00e9r\u00eat d\u2019utiliser un v\u00e9lo pour nos d\u00e9placements quotidiens.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le transport de charges lourdes et volumineuses reste cependant un obstacle important avec un v\u00e9lo classique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019alternative entre le v\u00e9lo classique et la voiture personnelle pour ce type de transport peut \u00eatre le v\u00e9lo cargo. Et le d\u00e9veloppement des ventes de v\u00e9los cargo en est la preuve.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais les tarifs sont tr\u00e8s \u00e9lev\u00e9s surtout si l\u2019on veut un mod\u00e8le \u00e9lectrique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u2019est ce constat qui est \u00e0 l\u2019origine de notre d\u00e9marche de conception d\u2019un mod\u00e8le vendu en kit. Mais nous vendons \u00e9galement des v\u00e9los compl\u00e8tement assembl\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce mod\u00e8le en kit permet de recycler un VTT inutilis\u00e9. Tous ces composants sont r\u00e9utilis\u00e9s pour avoir une seconde vie. C\u2019est ce qu\u2019on appelle l\u2019\u00e9conomie circulaire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous aborderons ensuite un aspect tr\u00e8s important qui est la durabilit\u00e9 et bien sur la r\u00e9parabilit\u00e9 des produits.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les cadres de nos v\u00e9los sont con\u00e7us en t\u00f4le de haute r\u00e9sistance, d\u00e9coup\u00e9es au laser, pli\u00e9es et prot\u00e9g\u00e9es par un traitement anticorrosion et une peinture \u00e9poxy. Ils sont ensuite assembl\u00e9s par des rivets de structure. La fabrication ne n\u00e9cessite pas de savoir souder.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous apportons un soin particulier pour que toutes les pi\u00e8ces que nous fabriquons pour nos cadres soient r\u00e9parables.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous utilisons toujours des composants les plus adapt\u00e9 \u00e0 leur usage.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous d\u00e9taillerons chaque composant utilis\u00e9 et expliquerons les raisons de nos choix.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"608\" src=\"http:\/\/www.lesvelosdarthur.fr\/lesvelosdarthur\/wp-content\/uploads\/2025\/01\/Velo-noir-1024x608.jpg\" alt=\"\" class=\"wp-image-745\" srcset=\"https:\/\/www.lesvelosdarthur.fr\/lesvelosdarthur\/wp-content\/uploads\/2025\/01\/Velo-noir-1024x608.jpg 1024w, https:\/\/www.lesvelosdarthur.fr\/lesvelosdarthur\/wp-content\/uploads\/2025\/01\/Velo-noir-300x178.jpg 300w, https:\/\/www.lesvelosdarthur.fr\/lesvelosdarthur\/wp-content\/uploads\/2025\/01\/Velo-noir-768x456.jpg 768w, https:\/\/www.lesvelosdarthur.fr\/lesvelosdarthur\/wp-content\/uploads\/2025\/01\/Velo-noir-1536x912.jpg 1536w, https:\/\/www.lesvelosdarthur.fr\/lesvelosdarthur\/wp-content\/uploads\/2025\/01\/Velo-noir-2048x1216.jpg 2048w\" sizes=\"auto, (max-width: 706px) 89vw, (max-width: 767px) 82vw, 740px\" \/><figcaption class=\"wp-element-caption\">binary comment<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Nous d\u00e9marrons ici une s\u00e9rie de publications concernant notre conception et vision du v\u00e9lo et plus particuli\u00e8rement dans un premier temps celles du v\u00e9lo cargo. Nous apporterons \u00e9galement des informations sur l\u2019actualit\u00e9 du v\u00e9lo. Nous sommes aujourd\u2019hui de plus en plus nombreux \u00e0 comprendre l\u2019int\u00e9r\u00eat d\u2019utiliser un v\u00e9lo pour nos d\u00e9placements quotidiens. Le transport de &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.lesvelosdarthur.fr\/index.php\/2025\/01\/12\/pourquoi-le-velo-cargo-en-kit\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Pourquoi le v\u00e9lo cargo en kit ?&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-744","post","type-post","status-publish","format-standard","hentry","category-le-concept"],"_links":{"self":[{"href":"https:\/\/www.lesvelosdarthur.fr\/index.php\/wp-json\/wp\/v2\/posts\/744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesvelosdarthur.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesvelosdarthur.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesvelosdarthur.fr\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesvelosdarthur.fr\/index.php\/wp-json\/wp\/v2\/comments?post=744"}],"version-history":[{"count":1,"href":"https:\/\/www.lesvelosdarthur.fr\/index.php\/wp-json\/wp\/v2\/posts\/744\/revisions"}],"predecessor-version":[{"id":746,"href":"https:\/\/www.lesvelosdarthur.fr\/index.php\/wp-json\/wp\/v2\/posts\/744\/revisions\/746"}],"wp:attachment":[{"href":"https:\/\/www.lesvelosdarthur.fr\/index.php\/wp-json\/wp\/v2\/media?parent=744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesvelosdarthur.fr\/index.php\/wp-json\/wp\/v2\/categories?post=744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesvelosdarthur.fr\/index.php\/wp-json\/wp\/v2\/tags?post=744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}